{"id":1002997,"date":"2026-05-27T09:08:36","date_gmt":"2026-05-27T13:08:36","guid":{"rendered":""},"modified":"2026-05-27T09:15:24","modified_gmt":"2026-05-27T13:15:24","slug":"el-costo-del-combustible-dispara-la-inflacion-en-la-isla","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260527\/el-costo-del-combustible-dispara-la-inflacion-en-la-isla\/","title":{"rendered":"El costo del combustible dispara la inflaci\u00f3n en la isla"},"content":{"rendered":"<p>Con un alza de 23.5% mes a mes y 30.7% interanual en el combustible, la inflaci\u00f3n en Puerto Rico se dispar\u00f3 en abril con un incremento de 1.6% al comparar con marzo y de 4% al mirar los n\u00fameros de marzo del a\u00f1o pasado.<\/p>\n\n\n\n<p>As\u00ed se refleja en el bolsillo del consumidor el ataque de Israel y Estados Unidos al pa\u00eds petrolero de Ir\u00e1n.<\/p>\n\n\n\n<p>Seg\u00fan el \u00cdndice de Precios al Consumidor, publicado por el Departamento del Trabajo y Recursos Humanos, los principales aumentos al contrastar con marzo fueron en el segmento de transportaci\u00f3n (6.3%), alimentos y bebidas (0.7%) y educaci\u00f3n y comunicaci\u00f3n (0.5%).<\/p>\n\n\n\n<p>De hecho, en la comparativa interanual el costo de la transportaci\u00f3n aument\u00f3 3.3%. Esto se debi\u00f3 al aumento en el costo de la transportaci\u00f3n en masa, con una subida de 13.1% a ra\u00edz del incremento en las tarifas de transportaci\u00f3n a\u00e9rea.<\/p><div class=\"notic-content-middle\" id=\"notic-2779928873\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>En el grupo de alimentos y bebidas, el aumento 0.7% mes a mes y 2.6% interanual se concretiz\u00f3 en gran parte por un aumento en los alimentos consumidor en el hogar. El subrupo mayormente responsable de esta alza fue: frutas y vegetales, que reflej\u00f3 una subida de 1.9% provocado en mayor medida por los nuevos precios de los tomates.<\/p>\n\n\n\n<p>Otro aumento notable fue el de matr\u00edcula de colegios y academias (0.9%).<\/p>\n\n\n\n<p>El poder adquisitivo del d\u00f3lar se redujo de 71 centavos a 70 centavos entre marzo y abril.<\/p>","protected":false},"excerpt":{"rendered":"<p>Con un alza de 23.5% mes a mes y 30.7% interanual en el combustible, la inflaci\u00f3n en Puerto Rico se dispar\u00f3 en abril con un incremento de 1.6% al comparar con marzo y de 4% al mirar los n\u00fameros de marzo del a\u00f1o pasado. As\u00ed se refleja en el bolsillo del consumidor el ataque de [&hellip;]<\/p>","protected":false},"author":2736,"featured_media":534335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,3,2],"tags":[1899,802,2306],"class_list":["post-1002997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-noticias","category-ultima-hora","tag-gasolina","tag-inflacion","tag-precios"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1002997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/2736"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1002997"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1002997\/revisions"}],"predecessor-version":[{"id":1003000,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1002997\/revisions\/1003000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/534335"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1002997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1002997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1002997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}