{"id":100247,"date":"2015-11-11T07:01:00","date_gmt":"2015-11-11T11:01:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20151111\/miguel-romero-se-lanza-para-el-senado-video\/"},"modified":"2025-07-18T08:40:37","modified_gmt":"2025-07-18T08:40:37","slug":"miguel-romero-se-lanza-para-el-senado-video","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20151111\/miguel-romero-se-lanza-para-el-senado-video\/","title":{"rendered":"Miguel Romero se lanza para el Senado (v\u00eddeo)"},"content":{"rendered":"<p>El exsecretario de la Gobernaci\u00f3n, Miguel Romero, anunci\u00f3 el miercoles su intenci\u00f3n de aspirar a un esca\u00f1o senatorial por el distrito de San Juan, Guaynabo y Aguas Buenas en las pr\u00f3ximas elecciones.<\/p>\n<p>Anteriormente Romero intent\u00f3 ganar una contienda primarista para ser el presidente del Partido Nuevo Progresista (PNP) en San Juan.<\/p>\n<p>En un mensaje por v\u00eddeo publicado en su p\u00e1gina de Facebook, Romero indic\u00f3 que &#8216;al igual que t\u00fa, vivo preocupado por el rumbo que lleva Puerto Rico. La crisis econ\u00f3mica y social por la cual atraviesa nuestra Isla es tan grave que no tiene precedentes. Es triste y alarmante presenciar como la emigraci\u00f3n en b\u00fasqueda de mejores oportunidades provoca la separaci\u00f3n de miles de familias puertorrique\u00f1as&#8217;.<\/p>\n<p>Destac\u00f3 que si algo hemos aprendido &#8216;es que las elecciones s\u00ed tienen consecuencias&#8217;.<\/p>\n<p>A\u00f1adi\u00f3 que la Legislatura tiene que transformarse y convertirse en una verdadera &#8216;herramienta del Pueblo&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-3946649349\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>(function(d, s, id) { var js, fjs = d.getElementsByTagName(s)[0]; if (d.getElementById(id)) return; js = d.createElement(s); js.id = id; js.src = &#8216;\/\/connect.facebook.net\/en_GB\/sdk.js#xfbml=1&amp;version=v2.3&#8217;; fjs[removed].insertBefore(js, fjs);}(document, &#8216;script&#8217;, &#8216;facebook-jssdk&#8217;));<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/miguelromero51\/videos\/1239668556048859\/\">Juntos podemos transformar a Puerto Rico!<\/a><\/p>\n<p>Hoy, me complace anunciarte que he tomado la decisi\u00f3n de participar activamente en la transformaci\u00f3n de Puerto Rico.<\/p>\n<p>Posted by<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/miguelromero51\/\">Miguel Romero<\/a> on Wednesday, 11 November 2015<\/p>","protected":false},"excerpt":{"rendered":"<p>El exsecretario de la Gobernaci\u00f3n, Miguel Romero, anunci\u00f3 el miercoles su intenci\u00f3n de aspirar a un esca\u00f1o senatorial por el distrito de San Juan, Guaynabo y Aguas Buenas en las pr\u00f3ximas elecciones. Anteriormente Romero intent\u00f3 ganar una contienda primarista para ser el presidente del Partido Nuevo Progresista (PNP) en San Juan. En un mensaje por [&hellip;]<\/p>","protected":false},"author":0,"featured_media":500650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-100247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=100247"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100247\/revisions"}],"predecessor-version":[{"id":500651,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100247\/revisions\/500651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/500650"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=100247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=100247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=100247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}