{"id":1001606,"date":"2026-05-21T05:47:00","date_gmt":"2026-05-21T09:47:00","guid":{"rendered":""},"modified":"2026-05-21T08:01:35","modified_gmt":"2026-05-21T12:01:35","slug":"la-enfermedad-renal-cronica-sigue-en-aumento-en-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260521\/la-enfermedad-renal-cronica-sigue-en-aumento-en-puerto-rico\/","title":{"rendered":"La enfermedad renal cr\u00f3nica sigue en aumento en Puerto Rico"},"content":{"rendered":"<p>La enfermedad renal cr\u00f3nica (ERC) contin\u00faa en aumento en Puerto Rico, con 6,502 pacientes en di\u00e1lisis en el pa\u00eds mientras persiste la necesidad de mejorar los servicios de prevenci\u00f3n, especialmente en poblaciones vulnerables. <\/p>\n\n\n\n<p>As\u00ed lo revel\u00f3 el Consejo Renal de Puerto Rico al presentar los datos que recopil\u00f3 en un censo este a\u00f1o, que est\u00e1n disponibles en la primera aplicaci\u00f3n que visibiliza estad\u00edsticas de la poblaci\u00f3n de pacientes en di\u00e1lisis en la isla.<\/p>\n\n\n\n<p>Brendalis Pacheco, directora ejecutiva del Consejo Renal de Puerto Rico, expres\u00f3 su preocupaci\u00f3n ante los datos recopilados en el censo de pacientes renales, que comparan con los 6,483 pacientes que hab\u00eda en el 2025. Desde el pasado a\u00f1o al presente, hubo pacientes renales que fallecieron pero a\u00fan as\u00ed creci\u00f3 la cantidad de nuevos pacientes en di\u00e1lisis. <\/p>\n\n\n\n<p>\u201cEstas cifras confirman lo que hemos advertido por a\u00f1os: la enfermedad renal cr\u00f3nica sigue en aumento en Puerto Rico, afectando desproporcionadamente a comunidades vulnerables, envejecientes y personas con condiciones como diabetes e hipertensi\u00f3n. Cada n\u00famero representa una vida interrumpida, familias que enfrentan di\u00e1lisis o trasplantes, y un sistema de salud presionado al l\u00edmite\u201d.<\/p>\n\n\n\n<p>La nueva aplicaci\u00f3n web est\u00e1 disponible en <a href=\"https:\/\/miconsejorenal.com\/\">miconsejorenal.com<\/a> e incluye un censo de los pacientes en di\u00e1lisis para abril de 2026. Los datos, provenientes de 51 centros de di\u00e1lisis en Puerto Rico, fueron recopilados y analizados por el Consejo Renal de Puerto Rico. Las cifras revelaron que hay un total de 6,502 pacientes en di\u00e1lisis en Puerto Rico. De estos, 5,570 pacientes est\u00e1n en hemodi\u00e1lisis presencial en los centros, con solo 738 pacientes que reciben di\u00e1lisis en modalidad peritoneal o en sus casas.<\/p>\n\n\n\n<p>\u201cQue el 85.7% de nuestros pacientes dependa de hemodi\u00e1lisis presencial nos confirma que hemos llegado tarde en demasiados casos\u201d, lament\u00f3 Pacheco. \u201cEl diagn\u00f3stico temprano sigue siendo nuestra deuda m\u00e1s grave. Pero estos datos locales nos dan el mapa: el 61.8% de los pacientes en di\u00e1lisis son hombres, lo que nos obliga a enfocar la detecci\u00f3n primaria en la poblaci\u00f3n masculina, tradicionalmente menos proclive a buscar ayuda m\u00e9dica preventiva\u201d.<\/p>\n\n\n\n<p>De los 51 centros de di\u00e1lisis activos en la Isla, 19 no ofrecen di\u00e1lisis en el hogar, lo que representa el 37% de las unidades sin esta modalidad disponible. \u201cEl hecho de que solo el 11.4% de los pacientes est\u00e9 en modalidad peritoneal o domiciliaria no es una debilidad: es una oportunidad de expansi\u00f3n inmensa. Y al ver que los corredores metro\/norte y sur concentran la mayor carga, queda claro que ah\u00ed deben centrarse los esfuerzos de detecci\u00f3n temprana y los programas de educaci\u00f3n comunitaria. Los datos locales no son solo n\u00fameros; son la br\u00fajula para una pol\u00edtica p\u00fablica efectiva\u201d, asegur\u00f3 Pacheco.<\/p>\n\n\n\n<p>La aplicaci\u00f3n web cuenta con un visualizador de datos del censo de pacientes renales, incluyendo los indicadores claves, distribuci\u00f3n por sexo y modalidad, comparativa de pacientes por regi\u00f3n y municipios de Puerto Rico, as\u00ed como <em>insights<\/em> epidemiol\u00f3gicos. El Consejo Renal actualizar\u00e1 estos datos trimestralmente, para poder monitorear el panorama de la poblaci\u00f3n en di\u00e1lisis. Adem\u00e1s, esperan integrar m\u00e1s informaci\u00f3n relevante sobre las enfermedades renales y los servicios disponibles para pacientes.<\/p>\n\n\n\n<p>Pacheco enfatiz\u00f3 que la aplicaci\u00f3n del Consejo Renal tambi\u00e9n incluye valiosos recursos para los pacientes renales, como un directorio de los centros de di\u00e1lisis, hospitales, cl\u00ednicas y centros de apoyo que ofrecen servicios a esta poblaci\u00f3n en Puerto Rico. Asimismo, cuenta con recetas nutritivas y art\u00edculos educativos sobre salud renal.<\/p>\n\n\n\n<p>El Consejo Renal de Puerto Rico es una organizaci\u00f3n sin fines de lucro dedicada a reducir el impacto de las enfermedades renales en nuestra poblaci\u00f3n. Su trabajo se enfoca en promover la prevenci\u00f3n, educar a la comunidad y facilitar la detecci\u00f3n temprana de condiciones que pueden afectar la salud de los ri\u00f1ones. <\/p>","protected":false},"excerpt":{"rendered":"<p>La enfermedad renal cr\u00f3nica (ERC) contin\u00faa en aumento en Puerto Rico, con 6,502 pacientes en di\u00e1lisis en el pa\u00eds mientras persiste la necesidad de mejorar los servicios de prevenci\u00f3n, especialmente en poblaciones vulnerables. As\u00ed lo revel\u00f3 el Consejo Renal de Puerto Rico al presentar los datos que recopil\u00f3 en un censo este a\u00f1o, que est\u00e1n [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1001609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,3],"tags":[5811,5810,1186],"class_list":["post-1001606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-noticias","tag-diagnostico-2","tag-enfermedad-renal","tag-prevencion"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1001606"}],"version-history":[{"count":3,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001606\/revisions"}],"predecessor-version":[{"id":1001734,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001606\/revisions\/1001734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1001609"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1001606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1001606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1001606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}