{"id":1001373,"date":"2026-05-19T13:58:38","date_gmt":"2026-05-19T17:58:38","guid":{"rendered":""},"modified":"2026-05-19T16:54:59","modified_gmt":"2026-05-19T20:54:59","slug":"alcalde-de-catano-califica-como-errores-administrativos-informe-de-la-contralora","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260519\/alcalde-de-catano-califica-como-errores-administrativos-informe-de-la-contralora\/","title":{"rendered":"Alcalde de Cata\u00f1o califica como errores administrativos informe de la contralora"},"content":{"rendered":"<p>El alcalde de Cata\u00f1o, Julio Alicea Vasallo, calific\u00f3 el martes la mayor\u00eda de los se\u00f1alamientos del informe OC-26-29 de la Oficina de la Contralora como errores administrativos que est\u00e1n en proceso de corregirse o que ya fueron corregidos.<\/p>\n\n\n\n<p>\u201cSi me presentan la prueba o cualquier otra evidencia que me convenza de que tengo que tomar una acci\u00f3n correctiva administrativa, yo lo voy a hacer. Claro que lo voy a hacer\u201d, dijo el alcalde en conferencia de prensa.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Alcalde de Cata\u00f1o abandona rueda de prensa por preguntas sobre se\u00f1alamientos de la Contralor\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/HvJcC7wIddI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Alicea Vasallo insisti\u00f3 adem\u00e1s en que se le debi\u00f3 dar la oportunidad de responder a los se\u00f1alamientos antes de la divulgaci\u00f3n del informe, lo que, a su juicio, no representa un trato preferencial frente a otros alcaldes.<\/p>\n\n\n\n<p>\u201cBueno, t\u00fa est\u00e1s hablando de otros alcaldes que no tienen el bagaje ni la experiencia que yo tengo de 36 a\u00f1os. Yo soy auditor de profesi\u00f3n. Trabaj\u00e9 en la Oficina de \u00c9tica Gubernamental y, dentro de mis funciones, estaba compartir informaci\u00f3n con la Oficina del Contralor de Puerto Rico. Yo s\u00e9 c\u00f3mo se manejan estos temas. Venir ahora a decirle al municipio y a todos los jefes de gabinete y secretarios que, desde el 29 de marzo, se va a diferenciar entre una auditor\u00eda regular y una querella, eso no es justo\u201d, declar\u00f3.<\/p>\n\n\n\n<p>Alicea Vasallo culmin\u00f3 la conferencia cuando se le pregunt\u00f3 sobre los v\u00ednculos de algunos de los protagonistas mencionados en el informe.<\/p>\n\n\n\n<p>El alcalde no quiso contestar c\u00f3mo se llama la empleada que ocup\u00f3 interinamente la Oficina de Planificaci\u00f3n y que, seg\u00fan el hallazgo n\u00famero 4 del informe de la contralora Carmen Ana Vega Fournier, no cumpl\u00eda con los requisitos de ley para ocupar el puesto.<\/p>\n\n\n\n<p>Tampoco quiso responder si la empleada, Wandereliz Morales, es o fue su nuera.<\/p>\n\n\n\n<p>\u201cEso ya ellos mismos lo consultaron con la Oficina de \u00c9tica Gubernamental. De lo contrario, hubiera sido referida en el informe a la Oficina de \u00c9tica Gubernamental, y no lo hicieron\u201d, contest\u00f3 el alcalde.<\/p>\n\n\n\n<p>En el hallazgo n\u00famero 5 se alega que el municipio contrat\u00f3 los servicios de un bufete que excedi\u00f3 las cantidades m\u00e1ximas de facturaci\u00f3n sin enmendar los contratos correspondientes. Se le pregunt\u00f3 a Alicea Vasallo si alg\u00fan socio del bufete tiene o tuvo alg\u00fan v\u00ednculo o relaci\u00f3n familiar con \u00e9l y contest\u00f3 en la negativa.<\/p>\n\n\n\n<p>El hallazgo n\u00famero 2 alega que el municipio contrat\u00f3 una empresa de publicidad para desarrollar artes y elementos gr\u00e1ficos similares a los utilizados en la campa\u00f1a electoral del alcalde. Alicea Vasallo no quiso identificar a la empresa. Tampoco ofreci\u00f3 el nombre de la empleada de la Oficina de Ayuda al Ciudadano se\u00f1alada por supuestamente usar una computadora y cuentas oficiales para asuntos pol\u00edtico-partidistas.<\/p>\n\n\n\n<p>\u201cYo no voy a dar nombres aqu\u00ed. Que se encargue el Departamento de Justicia, si hay una investigaci\u00f3n criminal, administrativa o lo que sea. Lo que s\u00ed puedo asegurar es que nosotros ya tenemos una investigaci\u00f3n administrativa interna abierta y estamos cooperando con la Oficina de \u00c9tica Gubernamental\u201d, sostuvo.<\/p>","protected":false},"excerpt":{"rendered":"<p>El alcalde de Cata\u00f1o, Julio Alicea Vasallo, calific\u00f3 el martes la mayor\u00eda de los se\u00f1alamientos del informe OC-26-29 de la Oficina de la Contralora como errores administrativos que est\u00e1n en proceso de corregirse o que ya fueron corregidos. \u201cSi me presentan la prueba o cualquier otra evidencia que me convenza de que tengo que tomar [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1001376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[260,1152,5402],"class_list":["post-1001373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-catano","tag-contralora","tag-julio-alicea"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1001373"}],"version-history":[{"count":3,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001373\/revisions"}],"predecessor-version":[{"id":1001421,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1001373\/revisions\/1001421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1001376"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1001373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1001373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1001373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}