{"id":1000869,"date":"2026-05-16T13:06:50","date_gmt":"2026-05-16T17:06:50","guid":{"rendered":""},"modified":"2026-05-16T13:20:51","modified_gmt":"2026-05-16T17:20:51","slug":"siete-pesistas-listos-para-el-mundial-juvenil-en-colombia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260516\/siete-pesistas-listos-para-el-mundial-juvenil-en-colombia\/","title":{"rendered":"Siete pesistas listos para el Mundial Juvenil en Colombia"},"content":{"rendered":"<p>Un grupo de siete j\u00f3venes pesistas se preparan para participar en la edici\u00f3n 2026 del Campeonato Mundial Juvenil de Levantamiento de Pesas que tendr\u00e1 como sede la Ciudad de Cali, Colombia.<\/p>\n\n\n\n<p>El mundial, que organiza la Federaci\u00f3n Internacional de este deporte, se realizar\u00e1 del 5 al 11 de julio pr\u00f3ximo.<\/p>\n\n\n\n<p>La representaci\u00f3n Patria contar\u00e1 con Adyelis Col\u00f3n (48 kilogramos), Yoann P\u00e9rez (58 kg), Alanis S\u00e1nchez (63 kg) y Mia Col\u00f3n (+86 kg), quienes estar\u00e1n participando en la rama femenina. Mientras, la representaci\u00f3n en la rama masculina estar\u00e1 compuesta por \u00c1ngel Picart (79 kg), Dilan Palou (88 kg) y H\u00e9ctor P\u00e9rez (+94 kg).<\/p><div class=\"notic-content-middle\" id=\"notic-3260669277\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>\u201cNuestro equipo nacional juvenil es el resultado de los centros de formaci\u00f3n del deporte de la halterofilia y el esfuerzo de la Federaci\u00f3n de Levantamiento de Pesas de Puerto Rico. Le deseamos mucho \u00e9xito a cada uno de estos j\u00f3venes y estoy seguro de que har\u00e1n una gran representaci\u00f3n en el Mundial\u201d, expres\u00f3 el presidente de la Federaci\u00f3n de Levantamiento de Pesas de Puerto Rico, Andr\u00e9s Vargas.<\/p>\n\n\n\n<p>El grupo de pesistas hizo sus trabajos en sus respectivas ligas federativas y en los selectivos que trabaja la Federaci\u00f3n en conjunto con la preselecci\u00f3n mayor que se prepara para los Juegos Centroamericanos y del Caribe 2026.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"1024\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial-662x1024.jpeg\" alt=\"\" class=\"wp-image-1000871\" srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial-662x1024.jpeg 662w, https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial-194x300.jpeg 194w, https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial-768x1189.jpeg 768w, https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial-8x12.jpeg 8w, https:\/\/cdn.noticel.com\/2026\/05\/16131140\/Logo-Mundial.jpeg 827w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Un grupo de siete j\u00f3venes pesistas se preparan para participar en la edici\u00f3n 2026 del Campeonato Mundial Juvenil de Levantamiento de Pesas que tendr\u00e1 como sede la Ciudad de Cali, Colombia. El mundial, que organiza la Federaci\u00f3n Internacional de este deporte, se realizar\u00e1 del 5 al 11 de julio pr\u00f3ximo. La representaci\u00f3n Patria contar\u00e1 con [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1000870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[531,232,760],"class_list":["post-1000869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-campeonato-mundial","tag-colombia","tag-halterofilia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1000869"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000869\/revisions"}],"predecessor-version":[{"id":1000872,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000869\/revisions\/1000872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1000870"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1000869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1000869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1000869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}