{"id":1000818,"date":"2026-05-16T09:36:51","date_gmt":"2026-05-16T13:36:51","guid":{"rendered":"https:\/\/noticel.com\/?p=1000818"},"modified":"2026-05-16T09:46:25","modified_gmt":"2026-05-16T13:46:25","slug":"cuatro-blanqueadas-marcan-la-apertura-de-la-postemporada-2026","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260516\/cuatro-blanqueadas-marcan-la-apertura-de-la-postemporada-2026\/","title":{"rendered":"Cuatro blanqueadas marcan la apertura de la postemporada 2026"},"content":{"rendered":"<p>Cuatro equipos salieron airosos v\u00eda blanqueada este viernes en la apertura de la postemporada 2026 de la Liga de B\u00e9isbol Superior Doble A, que cont\u00f3 con acci\u00f3n en 15 estadios.<\/p>\n\n\n\n<p>Los Pescadores del Plata de Comer\u00edo, Toritos de Cayey, Titanes de Florida y Gigantes de Carolina repartieron nueve ceros a sus respectivos rivales para comenzar con el pie correcto las series semifinales de secci\u00f3n, pautadas a un m\u00e1ximo de cinco juegos.<\/p>\n\n\n\n<p>En la Central, los Pescadores del Plata sumaron su und\u00e9cima victoria consecutiva al blanquear 2-0 a los Criollos de Caguas con 13 ponches en ocho entradas del estelar zurdo Luis Leroy Cruz, quien apenas permiti\u00f3 dos hits. Kelvin Rom\u00e1n cerr\u00f3 el encuentro para apuntarse el salvamento. Mientras, los Toritos pintaron de blanco 1-0 a los Bravos de Cidra al combinar a Freddie Cabrera, Yadier Cruz y Ramesis Rosa. La \u00fanica carrera del juego la produjo Nelson Molina con cuadrangular en la parte baja de la sexta entrada.<\/p>\n\n\n\n<p>En el Norte, los Titanes vapulearon 16-0 a los Arenosos de Camuy con 18 imparables, incluyendo tres de Gaby Ayala, quien se qued\u00f3 a ley de un triple para completar el ciclo ofensivo. En total, remolc\u00f3 cuatro carreras y anot\u00f3 tres. La blanqueada fue obra de Christopher P\u00e9rez, Kevin L\u00f3pez, V\u00edctor Cepero y Wilfredo Rabassa.<\/p>\n\n\n\n<p>En la Metro, los Gigantes blanquearon 5-0 a los Lancheros de Cata\u00f1o con juego completo del derecho H\u00e9ctor Qui\u00f1ones, quien ponch\u00f3 a ocho y apenas permiti\u00f3 dos inatrapables. Kevin Mel\u00e9ndez encabez\u00f3 la ofensiva con jonr\u00f3n y dos carreras impulsadas. En la misma secci\u00f3n, los Guardianes pisaron el plato cuatro veces en la cuarta entrada para vencer 4-2 a los Maceteros de Vega Alta con 7.2 episodios de Mad Salgado.<\/p>\n\n\n\n<p>En el Este, los Artesanos de Las Piedras consiguieron su octava victoria consecutiva al dominar 3-2 a los Guerrilleros de R\u00edo Grande con seis entradas en cero y seis ponches del estelar Adalberto Flores. Adem\u00e1s, los campeones defensores Mulos de Juncos vencieron 6-3 a los Cariduros de Fajardo con tres anotaciones en la parte alta del noveno cap\u00edtulo. Brahiam Maldonado se hizo sentir por los Mulos con dos jonrones.<\/p>\n\n\n\n<p>En el Suroeste, los Petateros de Sabana Grande dejaron en el terreno 4-3 a los Piratas de Cabo Rojo con hit de oro de Joshua L\u00f3pez en la novena entrada. Por su parte, los Cafeteros de Yauco fabricaron cinco carreras en el tope del noveno episodio para vencer 7-3 a los Petroleros de Pe\u00f1uelas con tres remolcadas de Alcides Mart\u00ednez.<\/p><div class=\"notic-content-middle\" id=\"notic-2666889404\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>En el Sur, los Poetas de Juana D\u00edaz picaron al frente 3-2 sobre los Peces Voladores de Salinas con dos carreras impulsadas de Jadiel S\u00e1nchez. En otro resultado, los Maratonistas de Coamo hicieron sonar sus bates para apabullar 17-8 a los Brujos de Guayama con cuatro carreras remolcadas de Jonathan Garc\u00eda.<\/p>\n\n\n\n<p>En el Sureste, los Azucareros de Yabucoa superaron 5-1 a los Grises de Humacao con seis entradas de Noel Pinto y un cuadrangular de Kevin Santa. Tambi\u00e9n, los Jueyeros de Maunabo dominaron 4-3 a los Leones de Patillas con ramillete de cuatro carreras en el s\u00e9ptimo cap\u00edtulo. Jomar Huertas fue el lanzador ganador con ocho entradas y John Reyes consigui\u00f3 los \u00faltimos dos outs del encuentro con las bases llenas para apuntarse el salvamento.<\/p>\n\n\n\n<p><strong>Sorprenden a San Sebasti\u00e1n<br><\/strong><br>En el Noroeste, los Fundadores de A\u00f1asco detuvieron la cadena de seis triunfos de los Patrulleros de San Sebasti\u00e1n con marcador de 4-3, respaldados por un relevo de 4.2 entradas en cero de Alex de la Cruz y cuatro carreras remolcadas de Jorge Ortiz, quien conect\u00f3 un jonr\u00f3n y un sencillo.<\/p>\n\n\n\n<p>San Sebasti\u00e1n ven\u00eda de implantar una nueva marca en temporadas de 20 juegos en la fase regular con 19-1.<\/p>\n\n\n\n<p>Entretanto, los Libertadores de Hormigueros superaron 10-7 a los Tiburones de Aguadilla con dos carreras impulsadas de Carlos Lugo, Ram\u00f3n Agosto y Juli\u00e1n Figueroa.<\/p>\n\n\n\n<p><strong>Juegos para hoy s\u00e1bado:<br><\/strong>Las Piedras (1-0) en R\u00edo Grande (0-1)<br>Fajardo (0-1) en Juncos (1-0)<br>Yabucoa (1-0) en Humacao (0-1)<br>Maunabo (1-0) en Patillas (0-1)<br>San Sebasti\u00e1n (0-1) vs. A\u00f1asco (1-0) (en Mayag\u00fcez)<br>Hormigueros (1-0) en Aguadilla (0-1)<br>Cayey (1-0) en Cidra (0-1)<br>Comer\u00edo (1-0) en Caguas (0-1)<br>Camuy (0-1) en Florida (1-0)<br>Manat\u00ed vs. Hatillo (en Isabela)<br>Dorado (1-0) en Vega Alta (0-1)<br>Carolina (1-0) en Cata\u00f1o (0-1)<br>Juana D\u00edaz (1-0) en Salinas (0-1)<br>Guayama (0-1) vs. Coamo (1-0) (en Santa Isabel)<br>Sabana Grande (1-0) en Cabo Rojo (0-1)<br>Pe\u00f1uelas (0-1) en Yauco (1-0)<\/p>","protected":false},"excerpt":{"rendered":"<p>Cuatro equipos salieron airosos v\u00eda blanqueada este viernes en la apertura de la postemporada 2026 de la Liga de B\u00e9isbol Superior Doble A, que cont\u00f3 con acci\u00f3n en 15 estadios. Los Pescadores del Plata de Comer\u00edo, Toritos de Cayey, Titanes de Florida y Gigantes de Carolina repartieron nueve ceros a sus respectivos rivales para comenzar [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1000819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[32,31],"tags":[314,1640,2505],"class_list":["post-1000818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-beisbol-doble-a","tag-postemporada","tag-temporada-2026"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1000818"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000818\/revisions"}],"predecessor-version":[{"id":1000820,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000818\/revisions\/1000820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1000819"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1000818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1000818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1000818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}