{"id":1000659,"date":"2026-05-15T08:41:30","date_gmt":"2026-05-15T12:41:30","guid":{"rendered":""},"modified":"2026-05-15T11:44:05","modified_gmt":"2026-05-15T15:44:05","slug":"el-municipio-de-san-juan-no-quiere-pagar-la-fianza-de-10-para-impugnar-proyectos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260515\/el-municipio-de-san-juan-no-quiere-pagar-la-fianza-de-10-para-impugnar-proyectos\/","title":{"rendered":"El Municipio de San Juan no quiere pagar la fianza de 10% para impugnar proyectos"},"content":{"rendered":"<p>El Municipio de San Juan solicit\u00f3 ayer al Senado que no le aplique lo dispuesto en la nueva Ley 82-2026 que hace m\u00e1s caro y dif\u00edcil impugnar permisos otorgados a proyectos de infraestructura.<\/p>\n\n\n\n<p>Lo dispuesto en el nuevo estatuto est\u00e1 contenido en el proyecto de reforma de permisos que impulsa el gobierno. <\/p>\n\n\n\n<p>\u00abEntendemos que el requisito de fianza puede resultar oneroso. Por ello, recomendamos reevaluar esta disposici\u00f3n y que se disponga expresamente que el pago de fianza no aplicar\u00e1 a los municipios cuando estos son los querellantes\u00bb, dijo Gladys Maldonados Rodr\u00edguez, directora de la Oficina de Permisos del Municipio de San Juan, durante una vista senatorial sobre el proyecto.<\/p>\n\n\n\n<p>La reacci\u00f3n entre l\u00edderes comunitarios y expertos ante la firma de la ley por parte de la gobernadora Jenniffer Gonz\u00e1lez ha sido de condena. Por ejemplo, encarece significativamente impugnar en el tribunal o en la fase administrativa un permiso otorgado por el gobierno al incluir el requisito de pagar el 10% del total del valor del proyecto.<\/p><div class=\"notic-content-middle\" id=\"notic-1611194679\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>Ayer el secretario de la Gobernaci\u00f3n, Francisco Domenech, dijo a la prensa que la nueva ley y el requisito de la fianza no aplicaba al proceso administrativo.<\/p>\n\n\n\n<p>\u00abEl requisito mandatorio de fianza aqu\u00ed dispuesto, y el monto m\u00ednimo establecido por la misma, ser\u00e1 de aplicaci\u00f3n a todo procedimiento judicial o administrativo\u00bb, lee la ley. <\/p>\n\n\n\n<p>La nueva ley tiene otros efectos. Por ejemplo, el querellante tendr\u00e1 que probar que existe un da\u00f1o inminente, dispone que las omisiones procesales menores o subsanables que no causen da\u00f1os inmediatos ya no sirven como base legal para revocar un permiso y permite construcci\u00f3n en suelos r\u00fasticos especialmente protegidos si se catalogan como \u00abproyectos estrat\u00e9gicos\u00bb o de \u00abinfraestructura cr\u00edtica\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Municipio de San Juan solicit\u00f3 ayer al Senado que no le aplique lo dispuesto en la nueva Ley 82-2026 que hace m\u00e1s caro y dif\u00edcil impugnar permisos otorgados a proyectos de infraestructura. Lo dispuesto en el nuevo estatuto est\u00e1 contenido en el proyecto de reforma de permisos que impulsa el gobierno. \u00abEntendemos que el [&hellip;]<\/p>","protected":false},"author":2736,"featured_media":1000664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[919,3758],"class_list":["post-1000659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-fianza","tag-permisos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/2736"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1000659"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000659\/revisions"}],"predecessor-version":[{"id":1000708,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1000659\/revisions\/1000708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1000664"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1000659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1000659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1000659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}